{"id":100244,"date":"2023-07-04T07:49:18","date_gmt":"2023-07-04T07:49:18","guid":{"rendered":"https:\/\/abroadescape.com\/fr\/?page_id=100244"},"modified":"2026-05-09T13:42:41","modified_gmt":"2026-05-09T13:42:41","slug":"a-propos","status":"publish","type":"page","link":"https:\/\/abroadescape.com\/fr\/a-propos\/","title":{"rendered":"a propos"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_0 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_0 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><h1>\u00c0 propos d'Abroad Escape<\/h1>\n<\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><p>Abroad Escape est l'une des agences de placement de volontaires et de stagiaires les plus exp\u00e9riment\u00e9es d'Europe, avec des racines remontant \u00e0 2006. Nous pla\u00e7ons des volontaires et des stagiaires dans des programmes structur\u00e9s dans plus de 20 pays en Asie, en Afrique, en Am\u00e9rique du Sud et en Europe \u2014 couvrant l'enseignement, la conservation de la nature, la protection de la faune, la sant\u00e9, le d\u00e9veloppement communautaire et les stages internationaux.<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/pays-daction\/\">D\u00e9couvrir nos programmes<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_0 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/abroadescape.com\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/Vrijwilligerswerk-in-het-Buitenland.webp\" alt=\"Vrijwilligers in kleuterschool op filipijinen\" title=\"Vrijwilligerswerk in het Buitenland\" width=\"1200\" height=\"1006\" srcset=\"https:\/\/abroadescape.com\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/Vrijwilligerswerk-in-het-Buitenland.webp 1200w, https:\/\/abroadescape.com\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/Vrijwilligerswerk-in-het-Buitenland-980x822.webp 980w, https:\/\/abroadescape.com\/fr\/wp-content\/uploads\/sites\/2\/2026\/04\/Vrijwilligerswerk-in-het-Buitenland-480x402.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" class=\"wp-image-104740\" \/><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_1 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_2 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><h2>Un Message aux Parents : La S\u00e9curit\u00e9 Est Notre Priorit\u00e9<\/h2>\n<p>Nous comprenons qu'envoyer un fils ou une fille \u00e0 l'autre bout du monde est une \u00e9tape importante. C'est pourquoi l'ensemble de notre mod\u00e8le est construit autour d'un <strong>filet de s\u00e9curit\u00e9 24h\/24 et 7j\/7<\/strong>.<\/p>\n<p><strong>1. Infrastructure v\u00e9rifi\u00e9e :<\/strong> Nous utilisons des maisons de volontaires d\u00e9di\u00e9es et des moyens de transport r\u00e9pondant \u00e0 des exigences de s\u00e9curit\u00e9 strictes.<\/p>\n<p><strong>2. Accompagnement permanent :<\/strong> Il y a toujours un contact local d\u00e9sign\u00e9 sur place. Nos coordinateurs sont des professionnels exp\u00e9riment\u00e9s que nous connaissons personnellement.<\/p>\n<p><strong>3. Pr\u00e9paration professionnelle :<\/strong> Chaque participant re\u00e7oit avant le d\u00e9part un briefing complet sur la culture locale, la l\u00e9gislation et les protocoles de s\u00e9curit\u00e9.<\/p>\n<h3>Qui est responsable pendant le programme ?<\/h3>\n<p>Lorsque vous participez \u00e0 un programme Abroad Escape, vous n'\u00eates jamais seul(e). Nos programmes fonctionnent en partenariat avec des \u00e9quipes locales exp\u00e9riment\u00e9es, actives dans leur communaut\u00e9 tout au long de l'ann\u00e9e.<\/p>\n<p>Pour chaque destination, une structure claire est en place :<\/p>\n<ul>\n<li>Des coordinateurs locaux qui accueillent les participants \u00e0 l'arriv\u00e9e<\/li>\n<li>Des maisons de volontaires d\u00e9di\u00e9es et des h\u00e9bergements contr\u00f4l\u00e9s<\/li>\n<li>Une \u00e9quipe locale disponible 24h\/24 et 7j\/7 pour tout soutien<\/li>\n<li>Des proc\u00e9dures de s\u00e9curit\u00e9 claires et des protocoles d'urgence<\/li>\n<\/ul>\n<p>Abroad Escape reste \u00e9galement joignable apr\u00e8s votre d\u00e9part pour toute question ou soutien. Nous assurons un suivi actif de chaque placement et sommes en contact direct avec nos partenaires locaux tout au long du s\u00e9jour.<\/p>\n<p>Ce syst\u00e8me garantit que les participants et les parents savent exactement \u00e0 qui s'adresser \u2014 avant le d\u00e9part comme pendant le s\u00e9jour.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_2 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><h2>Quels sont les avantages du volontariat \u00e0 l'\u00e9tranger ?<\/h2>\n<p>Le volontariat \u00e0 l'\u00e9tranger offre bien plus que la chance d'avoir un impact positif \u2014 c'est une opportunit\u00e9 de d\u00e9couvrir de nouvelles cultures et de favoriser une croissance personnelle profonde. De nombreux participants rapportent que le volontariat renforce leur confiance en soi et d\u00e9veloppe des comp\u00e9tences qui leur sont utiles tout au long de leur carri\u00e8re.<\/p>\n<p>Le volontariat peut \u00eatre une exp\u00e9rience transformatrice. Il vous met en contact avec des cultures diff\u00e9rentes, ce qui \u00e9largit votre vision du monde. Il d\u00e9veloppe \u00e9galement des comp\u00e9tences pratiques telles que le leadership, le travail en \u00e9quipe et la r\u00e9solution de probl\u00e8mes \u2014 pr\u00e9cieuses aussi bien sur le plan personnel que professionnel. Les employeurs reconnaissent r\u00e9guli\u00e8rement la valeur unique de l'exp\u00e9rience et de la perspective qu'apporte le volontariat.<\/p>\n<p>Le volontariat vous aide \u00e9galement \u00e0 tisser un r\u00e9seau avec des personnes issues de milieux et de domaines vari\u00e9s. Cela ouvre des portes vers de nouvelles opportunit\u00e9s et peut mener \u00e0 de futurs stages ou emplois. Dans un march\u00e9 du travail de plus en plus comp\u00e9titif, ces exp\u00e9riences vous distinguent des autres candidats.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_3 et_pb_section et_section_regular et_block_section\">\n<div class=\"et_pb_row_3 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_4 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--1f09816e-184e-4ce5-a4cf-b39c52c423ca\"><div class=\"et_pb_text_inner\"><h2 style=\"text-align: left;\">Pourquoi choisir Abroad Escape ?<\/h2>\n<p style=\"text-align: left;\">Abroad Escape propose des programmes de haute qualit\u00e9, structur\u00e9s autour de l'int\u00e9grit\u00e9, de la s\u00e9curit\u00e9 et d'un accompagnement professionnel. Nous sommes l\u00e0 pour vous guider \u00e0 chaque \u00e9tape, afin que vous tiriez le meilleur de votre exp\u00e9rience.<\/p>\n<p style=\"text-align: left;\">Nous travaillons exclusivement avec des organisations locales qui emploient du personnel local, ont des objectifs communautaires d\u00e9finis et sont con\u00e7ues pour r\u00e9duire la d\u00e9pendance plut\u00f4t que de la cr\u00e9er. Vous vivez ainsi une exp\u00e9rience v\u00e9ritablement enrichissante tout en contribuant \u00e0 un changement durable.<\/p>\n<p style=\"text-align: left;\">Nous assurons un soutien local 24h\/24 pendant toute la dur\u00e9e du s\u00e9jour \u2014 que vous ayez des questions sur votre placement ou besoin d'aide en cas de probl\u00e8me, notre \u00e9quipe et nos coordinateurs locaux sont disponibles. Ce niveau d'accompagnement fait la diff\u00e9rence entre un voyage stressant et une exp\u00e9rience qui change une vie.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_4 et_pb_section et_section_regular et_block_section et_pb_section_parallax section_has_divider et_pb_bottom_divider\"><span class=\"et-pb-parallax-wrapper\"><span class=\"et-pb-parallax-background et-pb-parallax-background-module--divi-section-4\" style=\"background-image:url(https:\/\/abroadescape.com\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Molti-Background.png)\"><\/span><\/span>\n<div class=\"et_pb_row_4 et_pb_row et_block_row\">\n<div class=\"et_pb_column_5 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h5 style=\"text-align: center;\"><\/h5>\n<h2 class=\"mb-3\" style=\"text-align: center;\">T\u00e9moignages<span style=\"color: #ff8057;\">\u00a0Abroad Escape<\/span><\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et_block_row\">\n<div class=\"et_pb_column_6 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_1 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/wp-content\/uploads\/2023\/05\/Michael.jpg\" title=\"Michael\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\">Michael<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>J'ai fait du volontariat avec Abroad Escape, ce qui a \u00e9t\u00e9 sans aucun doute le meilleur voyage et la meilleure exp\u00e9rience de ma vie !<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_7 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_2 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/wp-content\/uploads\/2023\/05\/Kate.jpg\" title=\"Kate\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3>Kate<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Le programme a \u00e9t\u00e9 une exp\u00e9rience formidable pour moi. Les enfants \u00e0 qui j'ai enseign\u00e9 \u00e9taient tr\u00e8s intelligents et heureux. Ils \u00e9taient tr\u00e8s d\u00e9sireux d'apprendre, ce qui \u00e9tait incroyable.<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_8 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_3 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/wp-content\/uploads\/2023\/05\/jennifer.jpg\" title=\"jennifer\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\"><span>Jennifer<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_11 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>J'ai pass\u00e9 un excellent moment en tant que b\u00e9n\u00e9vole avec Abroad Escape. J'ai \u00e9t\u00e9 satisfait de toute l'exp\u00e9rience et j'aimerais y retourner \u00e0 l'avenir !<\/p>\n<p>&nbsp;<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_6 et_pb_row et_block_row\">\n<div class=\"et_pb_column_9 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_4 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Harry-Kenworthy.jpg\" title=\"Harry-Kenworthy\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_12 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\">Harry<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_13 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>J'ai particip\u00e9 au programme dans les merveilleuses \u00eeles Fidji et j'ai v\u00e9cu une exp\u00e9rience extraordinaire avec Abroad Escape !<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_10 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_5 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/fiji-Tyler.jpg\" title=\"fiji-Tyler\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_14 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3>Tyler<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_15 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Toute cette exp\u00e9rience m'a vraiment ouvert les yeux sur le monde et j'aimerais vraiment faire du b\u00e9n\u00e9volat \u00e0 nouveau.<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_11 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_6 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Marianne-test.jpg\" title=\"Marianne-test\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_16 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\"><span>Marie<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_17 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>C'est un super programme ! J'ai vraiment appr\u00e9ci\u00e9 mon temps parmi vous. Ce fut une exp\u00e9rience que je n'oublierai jamais.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_7 et_pb_row et_block_row\">\n<div class=\"et_pb_column_12 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_7 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Ben.jpg\" title=\"Ben\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_18 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\">Ben<\/h3>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_19 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>J'ai pass\u00e9 un si bon moment \u00e0 faire du b\u00e9n\u00e9volat. Ce fut vraiment une exp\u00e9rience qui a chang\u00e9 la vie.<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_13 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_8 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/test-Shilpa.jpg\" title=\"test-Shilpa\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_20 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\"><span>Shilpa<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_21 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Je peux honn\u00eatement dire que c'est l'une des exp\u00e9riences les plus extraordinaires que j'aie jamais v\u00e9cues.<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_14 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_9 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Carrie.jpg\" title=\"Carrie\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_22 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\"><span>Carrie<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_23 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Je ne pouvais pas imaginer avoir eu une meilleure exp\u00e9rience. Ce fut une exp\u00e9rience incroyablement enrichissante.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_8 et_pb_row et_block_row\">\n<div class=\"et_pb_column_15 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_10 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Victoria.jpg\" title=\"Victoria\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_24 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\">Victoria<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_25 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>La coordinatrice m'a fourni d'excellentes informations, notamment sur la culture et les habitants locaux. Elle m'a \u00e9galement donn\u00e9 beaucoup d'informations sur les environs et les bons endroits \u00e0 visiter. Ma coordinatrice est extr\u00eamement serviable et s'est surpass\u00e9e. Pendant ma semaine d'introduction, j'ai \u00e9t\u00e9 immerg\u00e9e dans la culture de Bali. La nourriture et le logement sont excellents. La nourriture est fra\u00eechement pr\u00e9par\u00e9e par les habitants et est toujours d\u00e9licieuse.<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_16 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_11 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Duygu.jpg\" title=\"Duygu\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_26 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3>Dugu<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_27 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Mon exp\u00e9rience au N\u00e9pal a \u00e9t\u00e9 positive \u00e0 bien des \u00e9gards. Le personnel est compos\u00e9 de personnes formidables avec lesquelles il est agr\u00e9able de travailler du d\u00e9but \u00e0 la fin. Il \u00e9tait fascinant de vivre parmi eux et de d\u00e9couvrir leur mode de vie et leurs traditions. Au cours des trois semaines pass\u00e9es avec Abroad Escape, j'ai appris et v\u00e9cu tant de belles choses, des souvenirs qui resteront \u00e0 jamais grav\u00e9s dans ma m\u00e9moire. Merci de m'avoir permis de vivre cette exp\u00e9rience unique.<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_17 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_12 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/denmark-vol.png\" title=\"denmark-vol\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_28 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\"><span>Sissel<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_29 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>C'\u00e9tait une exp\u00e9rience formidable, et j'aimerais bien recommencer.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_9 et_pb_row et_block_row\">\n<div class=\"et_pb_column_18 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_13 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Ladinathai-test-Ladina-1.jpg\" title=\"Ladinathai-test-Ladina-1\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_30 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\">Ladina<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_31 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Je me suis inscrite en Tha\u00eflande et j'ai vraiment appr\u00e9ci\u00e9. C'\u00e9tait une belle exp\u00e9rience !<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_19 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_14 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/Noor-nepal.jpg\" title=\"Noor-nepal\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_32 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3>Noor<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_33 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>J'ai pass\u00e9 un tr\u00e8s bon moment et j'ai beaucoup appris sur la culture et les gens. Les enfants et les gens ont \u00e9t\u00e9 tr\u00e8s gentils avec moi et j'ai ador\u00e9 faire des choses avec eux. Merci de m'avoir fait passer un bon moment !<\/p>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_20 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_image_15 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/abroadescape.com\/nl\/wp-content\/uploads\/sites\/4\/2023\/06\/annelies-pics.jpg\" title=\"annelies-pics\" \/><\/span><\/div>\n\n<div class=\"et_pb_text_34 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_de_mach_acf_item et_pb_de_mach_acf_item_0_tb_body et_pb_de_mach_alignment_center dmach-image-icon-placement-left\">\n<div class=\"et_pb_module_inner\">\n<div class=\"dmach-acf-item-containter\">\n<div class=\"dmach-acf-item-content\">\n<h3 class=\"dmach-acf-value\" style=\"text-align: left;\"><span>Anne<\/span><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_35 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>Le programme \u00e9tait bon et le soutien du coordinateur \u00e9tait merveilleux. Ces deux semaines ont \u00e9t\u00e9 les meilleures de ma vie. Je me suis sentie utile et sp\u00e9ciale en faisant partie de ce programme.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_5 et_pb_section et_section_regular et_block_section\">\n<div class=\"et_pb_row_10 et_pb_row et_block_row\" id=\"services\">\n<div class=\"et_pb_column_21 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_36 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Nos <span style=\"color: #ff8057;\">pays d'action<\/span><\/h3>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_11 et_pb_row et_block_row\" id=\"services\">\n<div class=\"et_pb_column_22 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_37 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Afrique<\/h3>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_12 et_pb_row et_block_row\">\n<div class=\"et_pb_column_23 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/cape-verde\/\">volontariat cape verde<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_24 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/kenya\/\">volontariat kenya<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_25 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_3_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_3 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/madagascar\/\">volontariat madagascar<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_13 et_pb_row et_block_row\">\n<div class=\"et_pb_column_26 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_4_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_4 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/malawi\/\">volontariat malawi<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_27 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_5_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_5 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/tanzanie\/\">volontariat tanzanie<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_28 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_6_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_6 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/zanzibar\/\">volontariat zanzibar<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_14 et_pb_row et_block_row\" id=\"services\">\n<div class=\"et_pb_column_29 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_38 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Asie<\/h3>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_15 et_pb_row et_block_row\">\n<div class=\"et_pb_column_30 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_7_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_7 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/bali\/\">volontariat bali<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_31 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_8_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_8 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/cambodge\/\">volontariat cambodge<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_32 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_9_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_9 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/core-du-sud\/\">volontariat core-du-sud<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_16 et_pb_row et_block_row\">\n<div class=\"et_pb_column_33 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_10_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_10 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/fidji\/\">volontariat fidji<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_34 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_11_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_11 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/inde\/\">volontariat inde<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_35 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_12_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_12 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/laos\/\">volontariat laos<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_17 et_pb_row et_block_row\">\n<div class=\"et_pb_column_36 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_13_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_13 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/nepal\/\">volontariat nepal<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_37 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_14_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_14 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/philippines\/\">volontariat philippines<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_38 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_15_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_15 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/sri-lanka\/\">volontariat sri lanka<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_18 et_pb_row et_block_row\">\n<div class=\"et_pb_column_39 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_16_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_16 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/philippines\/\">volontariat philippines<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_40 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_17_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_17 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/thailande\/\">volontariat thailande<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_41 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_18_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_18 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/vietnam\/\">volontariat vietnam<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_19 et_pb_row et_block_row\" id=\"services\">\n<div class=\"et_pb_column_42 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_39 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: center;\">Am\u00e9rique Latine<\/h3>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_20 et_pb_row et_block_row\">\n<div class=\"et_pb_column_43 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_19_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_19 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/abroadescape.com\/fr\/costa-rica\/\">volontariat costa rica<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_44 et_pb_column et_pb_column_1_3 et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n\n<div class=\"et_pb_column_45 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_6 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_21 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_46 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_blog_0 et_pb_blog et_pb_bg_layout_light et_pb_posts et_pb_module\"><div class=\"et_pb_ajax_pagination_container\"><div class=\"et_pb_posts et_grid_module\"><article class=\"et_pb_post et_pb_post_id_104884 clearfix et_pb_blog_item_0_0 post-104884 post type-post status-publish format-standard hentry category-stage\"><h2 class=\"entry-title\"><a href=\"https:\/\/abroadescape.com\/fr\/stage-medical-a-letranger-en-europe\/\">Stage m\u00e9dical \u00e0 l\u2019\u00e9tranger en Europe<\/a><\/h2><p class=\"post-meta\"><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><\/div><\/div><\/article><article class=\"et_pb_post et_pb_post_id_104625 clearfix et_pb_blog_item_0_1 post-104625 post type-post status-publish format-standard has-post-thumbnail hentry category-volontariat\"><h2 class=\"entry-title\"><a href=\"https:\/\/abroadescape.com\/fr\/meilleurs-programmes-de-volontariat-en-coree-du-sud\/\">Meilleurs Programmes de Volontariat en Cor\u00e9e du Sud<\/a><\/h2><p class=\"post-meta\"><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><\/div><\/div><\/article><article class=\"et_pb_post et_pb_post_id_104622 clearfix et_pb_blog_item_0_2 post-104622 post type-post status-publish format-standard has-post-thumbnail hentry category-volontariat\"><h2 class=\"entry-title\"><a href=\"https:\/\/abroadescape.com\/fr\/les-meilleurs-programmes-de-volontariat-au-vietnam\/\">Les Meilleurs Programmes de Volontariat au Vietnam<\/a><\/h2><p class=\"post-meta\"><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><\/div><\/div><\/article><article class=\"et_pb_post et_pb_post_id_104619 clearfix et_pb_blog_item_0_3 post-104619 post type-post status-publish format-standard has-post-thumbnail hentry category-volontariat\"><h2 class=\"entry-title\"><a href=\"https:\/\/abroadescape.com\/fr\/les-meilleurs-programmes-de-volontariat-en-thailande-2026\/\">Les Meilleurs Programmes de Volontariat en Tha\u00eflande 2026<\/a><\/h2><p class=\"post-meta\"><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><\/div><\/div><\/article><article class=\"et_pb_post et_pb_post_id_104616 clearfix et_pb_blog_item_0_4 post-104616 post type-post status-publish format-standard has-post-thumbnail hentry category-volontariat\"><h2 class=\"entry-title\"><a href=\"https:\/\/abroadescape.com\/fr\/volontariat-a-letranger-a-court-terme-vs-long-terme\/\">Volontariat \u00e0 l&#8217;\u00c9tranger \u00e0 Court Terme vs Long Terme<\/a><\/h2><p class=\"post-meta\"><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><\/div><\/div><\/article><article class=\"et_pb_post et_pb_post_id_104613 clearfix et_pb_blog_item_0_5 post-104613 post type-post status-publish format-standard has-post-thumbnail hentry category-volontariat\"><h2 class=\"entry-title\"><a href=\"https:\/\/abroadescape.com\/fr\/les-meilleures-destinations-de-volontariat-a-letranger-de-2026\/\">Les Meilleures Destinations de Volontariat \u00e0 l&#8217;\u00c9tranger de 2026<\/a><\/h2><p class=\"post-meta\"><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><\/div><\/div><\/article><article class=\"et_pb_post et_pb_post_id_104602 clearfix et_pb_blog_item_0_6 post-104602 post type-post status-publish format-standard hentry category-volontariat\"><h2 class=\"entry-title\"><a href=\"https:\/\/abroadescape.com\/fr\/meilleurs-programmes-de-volontariat-a-letranger-2026\/\">Meilleurs Programmes de Volontariat \u00e0 l&#8217;\u00c9tranger 2026<\/a><\/h2><p class=\"post-meta\"><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><\/div><\/div><\/article><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-100244","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/pages\/100244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/comments?post=100244"}],"version-history":[{"count":10,"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/pages\/100244\/revisions"}],"predecessor-version":[{"id":104887,"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/pages\/100244\/revisions\/104887"}],"wp:attachment":[{"href":"https:\/\/abroadescape.com\/fr\/wp-json\/wp\/v2\/media?parent=100244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}